{"id":4496,"date":"2024-12-24T00:00:00","date_gmt":"2024-12-23T23:00:00","guid":{"rendered":"https:\/\/savetibet.nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/"},"modified":"2025-10-27T14:09:18","modified_gmt":"2025-10-27T13:09:18","slug":"nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed","status":"publish","type":"nieuws","link":"https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/","title":{"rendered":"Nieuw Tibetaans woordenboek helpt taal beschermen tegen Chinese invloed"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Een enorm nieuw Tibetaans woordenboek van 223 delen en meer dan 300.000 woorden is vorige week aan de Library of Congress gepresenteerd. Dit project, de Monlam Grand Tibetan Dictionary, begon in 2012 op advies van de Dalai Lama en duurde negen jaar. Het woordenboek is volledig in het Tibetaanse schrift geschreven en behoort tot de grootste ter wereld.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Het project werd geleid door het Monlam Tibetan IT Research Centre in Dharamsala, India. Deze organisatie, gefinancierd door de Dalai Lama Trust, het Tibet Fund en USAID, ontwikkelt educatieve software. Alle 223 boeken zijn geschonken aan de Amerikaanse overheid en nu is er een gratis digitale versie beschikbaar via iOS en Android.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sikyong Penpa Tsering was aanwezig bij het belangrijke evenement, getiteld <\/span><i><span style=\"font-weight: 400;\">\u201cMonlam Grand Tibetan Dictionary: Modern Technology for Ancient Wisdom.\u201d<\/span><\/i><span style=\"font-weight: 400;\"> Tijdens de ceremonie presenteerde Geshe Lobsang Monlam, directeur van het onderzoekscentrum, het monumentale woordenboek aan het Amerikaanse volk via de Library of Congress. In zijn toespraak benadrukte Geshe Monlam de transformerende rol van AI bij het behoud en de bevordering van de Tibetaanse taal en haar rijke culturele erfgoed.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tijdens de ceremonie benadrukte het Amerikaanse congreslid Jim McGovern hoe belangrijk dit woordenboek is om de Tibetaanse taal te behouden. Hij wees ook op China&#8217;s pogingen om het Tibetaans te verdringen, zoals het verplichten van onderwijs in Mandarijn. Volgens Geshe Lobsang Monlam, directeur van het onderzoekscentrum, was het woordenboek een gezamenlijke inspanning van de gemeenschap.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Een enorm nieuw Tibetaans woordenboek van 223 delen en meer dan 300.000 woorden is vorige week aan de Library of Congress gepresenteerd.<\/p>\n","protected":false},"featured_media":7586,"template":"","meta":{"_acf_changed":false},"categorie":[],"news_tag":[],"class_list":["post-4496","nieuws","type-nieuws","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nieuw Tibetaans woordenboek helpt taal beschermen tegen Chinese invloed - Campaign for Tibet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nieuw Tibetaans woordenboek helpt taal beschermen tegen Chinese invloed - Campaign for Tibet\" \/>\n<meta property=\"og:description\" content=\"Een enorm nieuw Tibetaans woordenboek van 223 delen en meer dan 300.000 woorden is vorige week aan de Library of Congress gepresenteerd.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/\" \/>\n<meta property=\"og:site_name\" content=\"Campaign for Tibet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/internationalcampaignfortibetnederland\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T13:09:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/savetibet.eu\/wp-content\/uploads\/2025\/10\/Sikyong_Penpa_Tserings_7th_day_in_the_United_States.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@savetibetorg\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\\\/\",\"url\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\\\/\",\"name\":\"Nieuw Tibetaans woordenboek helpt taal beschermen tegen Chinese invloed - Campaign for Tibet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/savetibet.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Sikyong_Penpa_Tserings_7th_day_in_the_United_States.jpeg\",\"datePublished\":\"2024-12-23T23:00:00+00:00\",\"dateModified\":\"2025-10-27T13:09:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\\\/#primaryimage\",\"url\":\"https:\\\/\\\/savetibet.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Sikyong_Penpa_Tserings_7th_day_in_the_United_States.jpeg\",\"contentUrl\":\"https:\\\/\\\/savetibet.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Sikyong_Penpa_Tserings_7th_day_in_the_United_States.jpeg\",\"width\":1024,\"height\":684},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nieuw Tibetaans woordenboek helpt taal beschermen tegen Chinese invloed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/\",\"name\":\"Campaign for Tibet\",\"description\":\"LET OP: Het boek The Dalai Lama &amp; Havel | Warriors for Truth &amp; Love is opnieuw in druk en momenteel tijdelijk uitverkocht. De levertijd is daardoor langer dan u van ons gewend bent. Wij vragen om uw begrip en geduld.\",\"publisher\":{\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/#organization\",\"name\":\"Campaign for Tibet\",\"url\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/savetibet.eu\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-round.png\",\"contentUrl\":\"https:\\\/\\\/savetibet.eu\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-round.png\",\"width\":150,\"height\":150,\"caption\":\"Campaign for Tibet\"},\"image\":{\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/internationalcampaignfortibetnederland\\\/\",\"https:\\\/\\\/x.com\\\/savetibetorg\",\"https:\\\/\\\/www.instagram.com\\\/savetibeteurope\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ICTEurope\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nieuw Tibetaans woordenboek helpt taal beschermen tegen Chinese invloed - Campaign for Tibet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/","og_locale":"nl_NL","og_type":"article","og_title":"Nieuw Tibetaans woordenboek helpt taal beschermen tegen Chinese invloed - Campaign for Tibet","og_description":"Een enorm nieuw Tibetaans woordenboek van 223 delen en meer dan 300.000 woorden is vorige week aan de Library of Congress gepresenteerd.","og_url":"https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/","og_site_name":"Campaign for Tibet","article_publisher":"https:\/\/www.facebook.com\/internationalcampaignfortibetnederland\/","article_modified_time":"2025-10-27T13:09:18+00:00","og_image":[{"width":1024,"height":684,"url":"https:\/\/savetibet.eu\/wp-content\/uploads\/2025\/10\/Sikyong_Penpa_Tserings_7th_day_in_the_United_States.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@savetibetorg","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/","url":"https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/","name":"Nieuw Tibetaans woordenboek helpt taal beschermen tegen Chinese invloed - Campaign for Tibet","isPartOf":{"@id":"https:\/\/savetibet.eu\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/#primaryimage"},"image":{"@id":"https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/#primaryimage"},"thumbnailUrl":"https:\/\/savetibet.eu\/wp-content\/uploads\/2025\/10\/Sikyong_Penpa_Tserings_7th_day_in_the_United_States.jpeg","datePublished":"2024-12-23T23:00:00+00:00","dateModified":"2025-10-27T13:09:18+00:00","breadcrumb":{"@id":"https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/#primaryimage","url":"https:\/\/savetibet.eu\/wp-content\/uploads\/2025\/10\/Sikyong_Penpa_Tserings_7th_day_in_the_United_States.jpeg","contentUrl":"https:\/\/savetibet.eu\/wp-content\/uploads\/2025\/10\/Sikyong_Penpa_Tserings_7th_day_in_the_United_States.jpeg","width":1024,"height":684},{"@type":"BreadcrumbList","@id":"https:\/\/savetibet.eu\/nl\/nieuws\/nieuw-tibetaans-woordenboek-helpt-taal-beschermen-tegen-chinese-invloed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/savetibet.eu\/nl\/"},{"@type":"ListItem","position":2,"name":"Nieuw Tibetaans woordenboek helpt taal beschermen tegen Chinese invloed"}]},{"@type":"WebSite","@id":"https:\/\/savetibet.eu\/nl\/#website","url":"https:\/\/savetibet.eu\/nl\/","name":"Campaign for Tibet","description":"LET OP: Het boek The Dalai Lama &amp; Havel | Warriors for Truth &amp; Love is opnieuw in druk en momenteel tijdelijk uitverkocht. De levertijd is daardoor langer dan u van ons gewend bent. Wij vragen om uw begrip en geduld.","publisher":{"@id":"https:\/\/savetibet.eu\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/savetibet.eu\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/savetibet.eu\/nl\/#organization","name":"Campaign for Tibet","url":"https:\/\/savetibet.eu\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/savetibet.eu\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/savetibet.eu\/wp-content\/uploads\/2025\/05\/logo-round.png","contentUrl":"https:\/\/savetibet.eu\/wp-content\/uploads\/2025\/05\/logo-round.png","width":150,"height":150,"caption":"Campaign for Tibet"},"image":{"@id":"https:\/\/savetibet.eu\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/internationalcampaignfortibetnederland\/","https:\/\/x.com\/savetibetorg","https:\/\/www.instagram.com\/savetibeteurope\/","https:\/\/www.youtube.com\/user\/ICTEurope"]}]}},"_links":{"self":[{"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/nieuws\/4496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/nieuws"}],"about":[{"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/types\/nieuws"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/media\/7586"}],"wp:attachment":[{"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/media?parent=4496"}],"wp:term":[{"taxonomy":"categorie","embeddable":true,"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/categorie?post=4496"},{"taxonomy":"news_tag","embeddable":true,"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/news_tag?post=4496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}