{"id":3227,"date":"2012-10-08T00:00:00","date_gmt":"2012-10-07T22:00:00","guid":{"rendered":"https:\/\/savetibet.nl\/nieuws\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\/"},"modified":"2025-10-27T13:48:01","modified_gmt":"2025-10-27T12:48:01","slug":"minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega","status":"publish","type":"nieuws","link":"https:\/\/savetibet.eu\/nl\/nieuws\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\/","title":{"rendered":"Minister Rosenthal bespreekt Tibet, economie en mensenrechten met Chinese collega"},"content":{"rendered":"<p><b>Nieuwsbericht | 09-10-2012<\/p>\n<p><\/b>Minister Rosenthal heeft in Peking een gesprek gehad met zijn Chinese collega Yang Jiechi. Beide ministers bespraken de wederzijdse handel en investeringen en mogelijkheden tot uitbreiding daarvan.<\/p>\n<p>China verwelkomt de wens van Nederland om een nieuw consulaat-generaal te vestigen in de Chinese stad Chongqing in west China, de snelst groeiende regio in China. Formele aspecten daarvan moeten nog worden nog uitgewerkt.<\/p>\n<p>Voorafgaand aan de ontmoeting met zijn Chinese collega had Rosenthal een gesprek met vertegenwoordigers van Nederlandse bedrijven in China.<\/p>\n<p>China heeft de Nederlandse mensenrechtenambassadeur uitgenodigd voor het Bejing Human Rights Forum in december.<\/p>\n<p>Rosenthal stelde zijn collega Yang Jiechi voor om nieuwe mensenrechtenconsultaties te starten tussen China en Nederland. Hij vroeg Yang ook om de mensenrechtenambassadeur toestemming te geven voor een bezoek aan Tibet. Ook stelde Rosenthal het lot van specifieke mensenrechtenverdedigers in China aan de orde.<\/p>\n<p>De ministers bespraken verder internationale politieke kwesties en de rol van China in de internationale gemeenschap. Yang en Rosenthal wisselden onder meer standpunten uit over het conflict in Syrie, de nucleaire dreiging in Iran en Noord-Korea.<\/p>\n<p>Lees <a href=\"http:\/\/www.rijksoverheid.nl\/ministeries\/bz\/nieuws\/2012\/10\/09\/rosenthal-bespreekt-economie-en-mensenrechten-met-chinese-collega.html?ns_campaign=nieuwsberichten-ministerie-van-buitenlandse-zaken&amp;ns_channel=att\" target=\"_blank\" rel=\"noopener noreferrer\">hier meer<\/a> op website rijksoverheid.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nieuwsbericht | 09-10-2012 Minister Rosenthal heeft in Peking een gesprek gehad met zijn Chinese collega Yang Jiechi. Beide ministers bespraken de wederzijdse handel en investeringen en mogelijkheden tot uitbreiding daarvan. China verwelkomt de wens van Nederland om een nieuw consulaat-generaal te vestigen in de Chinese stad Chongqing in west China, de snelst groeiende regio in [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"categorie":[],"news_tag":[],"class_list":["post-3227","nieuws","type-nieuws","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Minister Rosenthal bespreekt Tibet, economie en mensenrechten met Chinese collega - Campaign for Tibet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/savetibet.eu\/nl\/nieuws\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minister Rosenthal bespreekt Tibet, economie en mensenrechten met Chinese collega - Campaign for Tibet\" \/>\n<meta property=\"og:description\" content=\"Nieuwsbericht | 09-10-2012 Minister Rosenthal heeft in Peking een gesprek gehad met zijn Chinese collega Yang Jiechi. Beide ministers bespraken de wederzijdse handel en investeringen en mogelijkheden tot uitbreiding daarvan. China verwelkomt de wens van Nederland om een nieuw consulaat-generaal te vestigen in de Chinese stad Chongqing in west China, de snelst groeiende regio in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/savetibet.eu\/nl\/nieuws\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\/\" \/>\n<meta property=\"og:site_name\" content=\"Campaign for Tibet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/internationalcampaignfortibetnederland\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T12:48:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@savetibetorg\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\\\/\",\"url\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\\\/\",\"name\":\"Minister Rosenthal bespreekt Tibet, economie en mensenrechten met Chinese collega - Campaign for Tibet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/#website\"},\"datePublished\":\"2012-10-07T22:00:00+00:00\",\"dateModified\":\"2025-10-27T12:48:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/nieuws\\\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minister Rosenthal bespreekt Tibet, economie en mensenrechten met Chinese collega\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/\",\"name\":\"Campaign for Tibet\",\"description\":\"LET OP: Het boek The Dalai Lama &amp; Havel | Warriors for Truth &amp; Love is opnieuw in druk en momenteel tijdelijk uitverkocht. De levertijd is daardoor langer dan u van ons gewend bent. Wij vragen om uw begrip en geduld.\",\"publisher\":{\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/#organization\",\"name\":\"Campaign for Tibet\",\"url\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/savetibet.eu\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-round.png\",\"contentUrl\":\"https:\\\/\\\/savetibet.eu\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-round.png\",\"width\":150,\"height\":150,\"caption\":\"Campaign for Tibet\"},\"image\":{\"@id\":\"https:\\\/\\\/savetibet.eu\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/internationalcampaignfortibetnederland\\\/\",\"https:\\\/\\\/x.com\\\/savetibetorg\",\"https:\\\/\\\/www.instagram.com\\\/savetibeteurope\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ICTEurope\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Minister Rosenthal bespreekt Tibet, economie en mensenrechten met Chinese collega - Campaign for Tibet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/savetibet.eu\/nl\/nieuws\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\/","og_locale":"nl_NL","og_type":"article","og_title":"Minister Rosenthal bespreekt Tibet, economie en mensenrechten met Chinese collega - Campaign for Tibet","og_description":"Nieuwsbericht | 09-10-2012 Minister Rosenthal heeft in Peking een gesprek gehad met zijn Chinese collega Yang Jiechi. Beide ministers bespraken de wederzijdse handel en investeringen en mogelijkheden tot uitbreiding daarvan. China verwelkomt de wens van Nederland om een nieuw consulaat-generaal te vestigen in de Chinese stad Chongqing in west China, de snelst groeiende regio in [&hellip;]","og_url":"https:\/\/savetibet.eu\/nl\/nieuws\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\/","og_site_name":"Campaign for Tibet","article_publisher":"https:\/\/www.facebook.com\/internationalcampaignfortibetnederland\/","article_modified_time":"2025-10-27T12:48:01+00:00","twitter_card":"summary_large_image","twitter_site":"@savetibetorg","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/savetibet.eu\/nl\/nieuws\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\/","url":"https:\/\/savetibet.eu\/nl\/nieuws\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\/","name":"Minister Rosenthal bespreekt Tibet, economie en mensenrechten met Chinese collega - Campaign for Tibet","isPartOf":{"@id":"https:\/\/savetibet.eu\/nl\/#website"},"datePublished":"2012-10-07T22:00:00+00:00","dateModified":"2025-10-27T12:48:01+00:00","breadcrumb":{"@id":"https:\/\/savetibet.eu\/nl\/nieuws\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/savetibet.eu\/nl\/nieuws\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/savetibet.eu\/nl\/nieuws\/minister-rosenthal-bespreekt-tibet-economie-en-mensenrechten-met-chinese-collega\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/savetibet.eu\/nl\/"},{"@type":"ListItem","position":2,"name":"Minister Rosenthal bespreekt Tibet, economie en mensenrechten met Chinese collega"}]},{"@type":"WebSite","@id":"https:\/\/savetibet.eu\/nl\/#website","url":"https:\/\/savetibet.eu\/nl\/","name":"Campaign for Tibet","description":"LET OP: Het boek The Dalai Lama &amp; Havel | Warriors for Truth &amp; Love is opnieuw in druk en momenteel tijdelijk uitverkocht. De levertijd is daardoor langer dan u van ons gewend bent. Wij vragen om uw begrip en geduld.","publisher":{"@id":"https:\/\/savetibet.eu\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/savetibet.eu\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/savetibet.eu\/nl\/#organization","name":"Campaign for Tibet","url":"https:\/\/savetibet.eu\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/savetibet.eu\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/savetibet.eu\/wp-content\/uploads\/2025\/05\/logo-round.png","contentUrl":"https:\/\/savetibet.eu\/wp-content\/uploads\/2025\/05\/logo-round.png","width":150,"height":150,"caption":"Campaign for Tibet"},"image":{"@id":"https:\/\/savetibet.eu\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/internationalcampaignfortibetnederland\/","https:\/\/x.com\/savetibetorg","https:\/\/www.instagram.com\/savetibeteurope\/","https:\/\/www.youtube.com\/user\/ICTEurope"]}]}},"_links":{"self":[{"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/nieuws\/3227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/nieuws"}],"about":[{"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/types\/nieuws"}],"wp:attachment":[{"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/media?parent=3227"}],"wp:term":[{"taxonomy":"categorie","embeddable":true,"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/categorie?post=3227"},{"taxonomy":"news_tag","embeddable":true,"href":"https:\/\/savetibet.eu\/nl\/wp-json\/wp\/v2\/news_tag?post=3227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}